{"id":2028,"date":"2022-07-14T18:16:47","date_gmt":"2022-07-14T09:16:47","guid":{"rendered":"https:\/\/acweb.mycafe24.com\/event\/"},"modified":"2022-12-12T17:24:49","modified_gmt":"2022-12-12T08:24:49","slug":"event","status":"publish","type":"page","link":"https:\/\/avenuechiett.co.kr\/zh-hans\/event\/","title":{"rendered":"Event"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2028\" class=\"elementor elementor-2028 elementor-418\">\n\t\t\t\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-7d4a861e elementor-section-height-min-height wd-section-stretch elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7d4a861e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3be5032c\" data-id=\"3be5032c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78b055af elementor-widget elementor-widget-heading\" data-id=\"78b055af\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Event<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-f4fe2f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"f4fe2f5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27aeb79\" data-id=\"27aeb79\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58b089f uael-post__filter-align-center elementor-widget elementor-widget-uael-posts\" data-id=\"58b089f\" data-element_type=\"widget\" data-settings=\"{&quot;classic_slides_to_show&quot;:5,&quot;classic_slides_to_show_mobile&quot;:2,&quot;classic_slides_to_show_tablet&quot;:2,&quot;classic_pagination_type&quot;:&quot;ajax&quot;}\" data-widget_type=\"uael-posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-post__header\">\n\t\t\t\t\t<div class=\"uael-post__header-filters-wrap\">\n\t\t\t<ul class=\"uael-post__header-filters\" aria-label=\"Taxonomy Filter\">\n\t\t\t\t<li class=\"uael-post__header-filter uael-filter__current\" data-filter=\"*\">All<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__body\">\n\t\t\t\n\t\t\n\t\t<div class=\"uael-blog-terms-position- uael-post-image-top uael-post-grid uael-posts\" data-query-type=\"custom\" data-structure=\"normal\" data-layout=\"\" data-page=\"2028\" data-skin=\"classic\" data-filter-default=\"All\" data-offset-top=\"30\" >\n\n\t\t\t\t\t\t\t<div class=\"uael-post-grid__inner uael-post__columns-5 uael-post__columns-tablet-2 uael-post__columns-mobile-2\">\n\t\t\t\n<div class=\"uael-post-wrapper %ec%a2%85%eb%a3%8c%eb%90%9c-%ec%9d%b4%eb%b2%a4%ed%8a%b8-zh-hans event-zh-hans  close event \">\n\t<div class=\"uael-post__bg-wrap\">\n\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/avenuechiett.co.kr\/zh-hans\/%e4%ba%a7%e5%93%81%e6%b4%bb%e5%8a%a8\/\" target=\"_self\" title=\"\u4ea7\u54c1\u6d3b\u52a8\"><img decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/avenuechiett.co.kr\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"attachment-full size-full wd-lazy-load woodmart-lazy-load wd-lazy-fade\" alt=\"\" data-wood-src=\"https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb.jpg\" data-srcset=\"https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb.jpg 600w, https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb-225x300.jpg 225w, https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb-350x467.jpg 350w, https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb-370x493.jpg 370w, https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb-255x340.jpg 255w, https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb-285x380.jpg 285w, https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb-150x200.jpg 150w\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap\">\n\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/avenuechiett.co.kr\/zh-hans\/%e4%ba%a7%e5%93%81%e6%b4%bb%e5%8a%a8\/\" target=\"_self\">\n\t\t\t\t\u4ea7\u54c1\u6d3b\u52a8\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper event-zh-hans %ec%a7%84%ed%96%89%ec%a4%91-%ec%9d%b4%eb%b2%a4%ed%8a%b8-zh-hans  event open \">\n\t<div class=\"uael-post__bg-wrap\">\n\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/avenuechiett.co.kr\/zh-hans\/%e4%ba%a7%e5%93%81%e8%b4%ad%e4%b9%b0%e6%b4%bb%e5%8a%a8\/\" target=\"_self\" title=\"\u4ea7\u54c1\u8d2d\u4e70\u6d3b\u52a8\"><img decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/avenuechiett.co.kr\/wp-content\/themes\/woodmart\/images\/lazy.png\" class=\"attachment-full size-full wd-lazy-load woodmart-lazy-load wd-lazy-fade\" alt=\"\" data-wood-src=\"https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb.jpg\" data-srcset=\"https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb.jpg 600w, https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb-225x300.jpg 225w, https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb-350x467.jpg 350w, https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb-370x493.jpg 370w, https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb-255x340.jpg 255w, https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb-285x380.jpg 285w, https:\/\/avenuechiett.co.kr\/wp-content\/uploads\/2022\/07\/event-thumb-150x200.jpg 150w\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap\">\n\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/avenuechiett.co.kr\/zh-hans\/%e4%ba%a7%e5%93%81%e8%b4%ad%e4%b9%b0%e6%b4%bb%e5%8a%a8\/\" target=\"_self\">\n\t\t\t\t\u4ea7\u54c1\u8d2d\u4e70\u6d3b\u52a8\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__footer\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Event All \uc774\ubca4\ud2b8 \ud14c\uc2a4\ud2b8 \uc5d0\ube44<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"_links":{"self":[{"href":"https:\/\/avenuechiett.co.kr\/zh-hans\/wp-json\/wp\/v2\/pages\/2028"}],"collection":[{"href":"https:\/\/avenuechiett.co.kr\/zh-hans\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/avenuechiett.co.kr\/zh-hans\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/avenuechiett.co.kr\/zh-hans\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/avenuechiett.co.kr\/zh-hans\/wp-json\/wp\/v2\/comments?post=2028"}],"version-history":[{"count":1,"href":"https:\/\/avenuechiett.co.kr\/zh-hans\/wp-json\/wp\/v2\/pages\/2028\/revisions"}],"predecessor-version":[{"id":2030,"href":"https:\/\/avenuechiett.co.kr\/zh-hans\/wp-json\/wp\/v2\/pages\/2028\/revisions\/2030"}],"wp:attachment":[{"href":"https:\/\/avenuechiett.co.kr\/zh-hans\/wp-json\/wp\/v2\/media?parent=2028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}