{"id":1672,"date":"2022-07-14T15:36:48","date_gmt":"2022-07-14T06:36:48","guid":{"rendered":"https:\/\/acweb.mycafe24.com\/avenuechiett-tv\/"},"modified":"2022-12-06T12:47:27","modified_gmt":"2022-12-06T03:47:27","slug":"avenuechiett-tv","status":"publish","type":"page","link":"https:\/\/avenuechiett.co.kr\/en\/avenuechiett-tv\/","title":{"rendered":"AvenueChiett TV"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1672\" class=\"elementor elementor-1672 elementor-259\">\n\t\t\t\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-40265fe0 elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wd-section-disabled\" data-id=\"40265fe0\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59010a5e\" data-id=\"59010a5e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4dc2dbae elementor-widget elementor-widget-heading\" data-id=\"4dc2dbae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">AvenueChiett TV\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4abcdf elementor-widget elementor-widget-heading\" data-id=\"b4abcdf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Meet the video where you can experience Avenue Chiett <\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-6a3168b elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"6a3168b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df0ac8d\" data-id=\"df0ac8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7c7816 elementor-widget elementor-widget-html\" data-id=\"f7c7816\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"about_nav\">\r\n\t\t\t\t<div class=\"wrap\">\r\n\t\t\t\t\t<ul class=\"about_sub_menu\">\r\n\t\t\t\t\t\t<li class=\"page_item page-item-14\"><a href=\"\/en\/avenuechiett-tv\/product-video\/\"><div class=\"t2\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2022\/11\/ac-comu-tab-icon-01-after-fix.png\"><\/img><\/div>Product Info<\/a><\/li>\r\n<li class=\"page_item page-item-16\"><a href=\"\/en\/avenuechiett-tv\/recipe\/\"><div class=\"t2\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2022\/11\/ac-comu-tab-icon-02-after-fix.png\"><\/img><\/div>Color Recipe<\/a><\/li>\r\n<li class=\"page_item page-item-18\"><a href=\"\/en\/avenuechiett-tv\/beauty-knowledge\/\"><div class=\"t2\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2022\/11\/ac-comu-tab-icon-03-after-fix.png\"><\/img><\/div>Beauti knowledge<\/a><\/li>\r\n\r\n\t\t\t\t\t<\/ul><!-- .about_sub_menu -->\r\n\t\t\t\t<\/div><!-- .wrap -->\r\n\t\t\t<\/div><!-- .about_nav -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-0d405b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"0d405b5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-299c744\" data-id=\"299c744\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a2a283 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6a2a283\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.7 - 03-07-2022 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#2c2c2c;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);-ms-flex-negative:0;flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:-webkit-box;display:-ms-flexbox;display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{-webkit-box-align:center;-ms-flex-align:center;align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;-webkit-box-flex:1;-ms-flex-positive:1;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{-webkit-box-flex:0;-ms-flex-positive:0;flex-grow:0;-ms-flex-negative:100;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{-webkit-box-flex:0;-ms-flex-positive:0;flex-grow:0;-ms-flex-negative:100;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c353aaf elementor-widget-mobile__width-auto elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"c353aaf\" data-element_type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;strikethrough&quot;,&quot;highlighted_text&quot;:&quot;view more&quot;,&quot;highlight_animation_duration&quot;:0,&quot;headline_style&quot;:&quot;highlight&quot;}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/acweb.mycafe24.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-animated-headline.min.css\">\t\t\t<a href=\"\/en\/avenuechiett-tv\/product-video\/\">\n\n\t\t\t\t\t<h1 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Product Info<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">view more<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h1>\n\t\t<\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb186e8 elementor-widget elementor-widget-grid\" data-id=\"bb186e8\" data-element_type=\"widget\" data-widget_type=\"grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n            <section class=\"portfolio-area style-1 noajax\" data-swp_ajaxid=\"bb186e8\" data-style=\"grid-style-two\">\n                <div class=\"swp-container\">\n                    <div class=\"modal\"><\/div>\n                    \n<div class=\"swp-row\">\n    <\/div>\n<div class=\"swpajaxapend\"><\/div><div class=\"swp-row \">\n    <div class=\"swp-col-lg-12 text-center\">\n        \n    <\/div>\n<\/div>                <\/div>\n            <\/section>\n\n        \n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-be91950 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"be91950\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11a8c35\" data-id=\"11a8c35\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-30625d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"30625d3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f456ada\" data-id=\"f456ada\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9b8e5a elementor-widget-mobile__width-auto elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"e9b8e5a\" data-element_type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;strikethrough&quot;,&quot;highlighted_text&quot;:&quot;view more&quot;,&quot;highlight_animation_duration&quot;:0,&quot;headline_style&quot;:&quot;highlight&quot;}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<a href=\"\/en\/avenuechiett-tv\/recipe\/\">\n\n\t\t\t\t\t<h1 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Color Recipe<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">view more<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h1>\n\t\t<\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1fb9c5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b1fb9c5\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eed9e3 elementor-widget elementor-widget-grid\" data-id=\"2eed9e3\" data-element_type=\"widget\" data-widget_type=\"grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n            <section class=\"portfolio-area style-1 noajax\" data-swp_ajaxid=\"2eed9e3\" data-style=\"grid-style-two\">\n                <div class=\"swp-container\">\n                    <div class=\"modal\"><\/div>\n                    \n<div class=\"swp-row\">\n    <\/div>\n<div class=\"swpajaxapend\"><\/div><div class=\"swp-row \">\n    <div class=\"swp-col-lg-12 text-center\">\n        \n    <\/div>\n<\/div>                <\/div>\n            <\/section>\n\n        \n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-d963436 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"d963436\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ada504\" data-id=\"4ada504\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-64b7c69 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"64b7c69\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5330b6c\" data-id=\"5330b6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c84d1e4 elementor-widget__width-auto elementor-widget-mobile__width-auto elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"c84d1e4\" data-element_type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;strikethrough&quot;,&quot;highlighted_text&quot;:&quot;view more&quot;,&quot;highlight_animation_duration&quot;:0,&quot;headline_style&quot;:&quot;highlight&quot;}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<a href=\"\/en\/avenuechiett-tv\/beauty-knowledge\/\">\n\n\t\t\t\t\t<h1 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Beauti knowledge<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">view more<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h1>\n\t\t<\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-23415de elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"23415de\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-312b7eb elementor-widget elementor-widget-grid\" data-id=\"312b7eb\" data-element_type=\"widget\" data-widget_type=\"grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n            <section class=\"portfolio-area style-1 noajax\" data-swp_ajaxid=\"312b7eb\" data-style=\"grid-style-two\">\n                <div class=\"swp-container\">\n                    <div class=\"modal\"><\/div>\n                    \n<div class=\"swp-row\">\n    <\/div>\n<div class=\"swpajaxapend\"><\/div><div class=\"swp-row \">\n    <div class=\"swp-col-lg-12 text-center\">\n        \n    <\/div>\n<\/div>                <\/div>\n            <\/section>\n\n        \n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>AvenueChiett TV Meet the video where you can experience Avenue Chiett Product Info Color Recipe Beauti knowledge Product Info view<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"_links":{"self":[{"href":"https:\/\/avenuechiett.co.kr\/en\/wp-json\/wp\/v2\/pages\/1672"}],"collection":[{"href":"https:\/\/avenuechiett.co.kr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/avenuechiett.co.kr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/avenuechiett.co.kr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/avenuechiett.co.kr\/en\/wp-json\/wp\/v2\/comments?post=1672"}],"version-history":[{"count":4,"href":"https:\/\/avenuechiett.co.kr\/en\/wp-json\/wp\/v2\/pages\/1672\/revisions"}],"predecessor-version":[{"id":1680,"href":"https:\/\/avenuechiett.co.kr\/en\/wp-json\/wp\/v2\/pages\/1672\/revisions\/1680"}],"wp:attachment":[{"href":"https:\/\/avenuechiett.co.kr\/en\/wp-json\/wp\/v2\/media?parent=1672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}